{"id":17714,"date":"2025-10-28T00:53:32","date_gmt":"2025-10-27T16:53:32","guid":{"rendered":"https:\/\/orfeostoryweb.com\/sosd\/?p=17714"},"modified":"2025-10-31T01:17:04","modified_gmt":"2025-10-30T17:17:04","slug":"hagrid","status":"publish","type":"post","link":"https:\/\/orfeostoryweb.com\/sosd\/hagrid\/","title":{"rendered":"Hagrid"},"content":{"rendered":"<p>Our sweetest gentleman, Hagrid, was rescued from Jurong Island. He\u2019s an older boy with a gentle spirit and a truly lovely soul. Hagrid has already started learning to walk on a leash and enjoys going for long, relaxing strolls. He\u2019s quite the curious sniffer! Of course, he also loves his snacks. We\u2019re hoping this wonderful boy finds a loving home with comfort and happiness.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Our sweetest gentleman, Hagrid, was rescued from Jurong Island. He\u2019s an older boy with a gentle spirit and a truly lovely soul. Hagrid has already started learning to walk on a leash and enjoys going for long, relaxing strolls. He\u2019s quite the curious sniffer! Of course, he also loves his snacks. We\u2019re hoping this wonderful [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":17717,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"give_campaign_id":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[102,98],"tags":[],"class_list":["post-17714","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dogs-profile","category-sponsor-a-dog"],"acf":{"photo_gallery":{"photo_gallery":[[{"id":17717,"title":"Hagrid","caption":"","full_image_url":"https:\/\/orfeostoryweb.com\/sosd\/wp-content\/uploads\/2025\/10\/Hagrid-e1761583917509.jpg","thumbnail_image_url":"https:\/\/orfeostoryweb.com\/sosd\/wp-content\/uploads\/2025\/10\/Hagrid-e1761583917509-150x150.jpg","large_srcset":"https:\/\/orfeostoryweb.com\/sosd\/wp-content\/uploads\/2025\/10\/Hagrid-e1761583917509.jpg 723w, https:\/\/orfeostoryweb.com\/sosd\/wp-content\/uploads\/2025\/10\/Hagrid-e1761583917509-300x191.jpg 300w, https:\/\/orfeostoryweb.com\/sosd\/wp-content\/uploads\/2025\/10\/Hagrid-e1761583917509-220x140.jpg 220w, https:\/\/orfeostoryweb.com\/sosd\/wp-content\/uploads\/2025\/10\/Hagrid-e1761583917509-500x319.jpg 500w","medium_srcset":"https:\/\/orfeostoryweb.com\/sosd\/wp-content\/uploads\/2025\/10\/Hagrid-e1761583917509-300x191.jpg 300w, https:\/\/orfeostoryweb.com\/sosd\/wp-content\/uploads\/2025\/10\/Hagrid-e1761583917509-220x140.jpg 220w, https:\/\/orfeostoryweb.com\/sosd\/wp-content\/uploads\/2025\/10\/Hagrid-e1761583917509-500x319.jpg 500w, https:\/\/orfeostoryweb.com\/sosd\/wp-content\/uploads\/2025\/10\/Hagrid-e1761583917509.jpg 723w","media_details":{"width":723,"height":461,"sizes":{"medium":{"file":"Hagrid-e1761583917509-300x191.jpg","width":300,"height":191,"mime-type":"image\/jpeg","filesize":9327,"source_url":"https:\/\/orfeostoryweb.com\/sosd\/wp-content\/uploads\/2025\/10\/Hagrid-e1761583917509-300x191.jpg"},"thumbnail":{"file":"Hagrid-e1761583917509-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":5173,"source_url":"https:\/\/orfeostoryweb.com\/sosd\/wp-content\/uploads\/2025\/10\/Hagrid-e1761583917509-150x150.jpg"},"woocommerce_thumbnail":{"file":"Hagrid-e1761583917509-220x140.jpg","width":220,"height":140,"mime-type":"image\/jpeg","filesize":6081,"source_url":"https:\/\/orfeostoryweb.com\/sosd\/wp-content\/uploads\/2025\/10\/Hagrid-e1761583917509-220x140.jpg"},"woocommerce_single":{"file":"Hagrid-e1761583917509-500x319.jpg","width":500,"height":319,"mime-type":"image\/jpeg","filesize":20827,"source_url":"https:\/\/orfeostoryweb.com\/sosd\/wp-content\/uploads\/2025\/10\/Hagrid-e1761583917509-500x319.jpg"},"woocommerce_gallery_thumbnail":{"file":"Hagrid-e1761583917509-100x100.jpg","width":100,"height":100,"mime-type":"image\/jpeg","filesize":3081,"source_url":"https:\/\/orfeostoryweb.com\/sosd\/wp-content\/uploads\/2025\/10\/Hagrid-e1761583917509-100x100.jpg"}}},"alt_text":"","url":"","target":""},{"id":17716,"title":"Hagrid2","caption":"","full_image_url":"https:\/\/orfeostoryweb.com\/sosd\/wp-content\/uploads\/2025\/10\/Hagrid2-e1761583933519.jpg","thumbnail_image_url":"https:\/\/orfeostoryweb.com\/sosd\/wp-content\/uploads\/2025\/10\/Hagrid2-e1761583933519-150x150.jpg","large_srcset":"https:\/\/orfeostoryweb.com\/sosd\/wp-content\/uploads\/2025\/10\/Hagrid2-e1761583933519.jpg 720w, https:\/\/orfeostoryweb.com\/sosd\/wp-content\/uploads\/2025\/10\/Hagrid2-e1761583933519-300x218.jpg 300w, https:\/\/orfeostoryweb.com\/sosd\/wp-content\/uploads\/2025\/10\/Hagrid2-e1761583933519-220x160.jpg 220w, https:\/\/orfeostoryweb.com\/sosd\/wp-content\/uploads\/2025\/10\/Hagrid2-e1761583933519-500x363.jpg 500w","medium_srcset":"https:\/\/orfeostoryweb.com\/sosd\/wp-content\/uploads\/2025\/10\/Hagrid2-e1761583933519-300x218.jpg 300w, https:\/\/orfeostoryweb.com\/sosd\/wp-content\/uploads\/2025\/10\/Hagrid2-e1761583933519-220x160.jpg 220w, https:\/\/orfeostoryweb.com\/sosd\/wp-content\/uploads\/2025\/10\/Hagrid2-e1761583933519-500x363.jpg 500w, https:\/\/orfeostoryweb.com\/sosd\/wp-content\/uploads\/2025\/10\/Hagrid2-e1761583933519.jpg 720w","media_details":{"width":720,"height":522,"sizes":{"medium":{"file":"Hagrid2-e1761583933519-300x218.jpg","width":300,"height":218,"mime-type":"image\/jpeg","filesize":20261,"source_url":"https:\/\/orfeostoryweb.com\/sosd\/wp-content\/uploads\/2025\/10\/Hagrid2-e1761583933519-300x218.jpg"},"thumbnail":{"file":"Hagrid2-e1761583933519-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":7646,"source_url":"https:\/\/orfeostoryweb.com\/sosd\/wp-content\/uploads\/2025\/10\/Hagrid2-e1761583933519-150x150.jpg"},"woocommerce_thumbnail":{"file":"Hagrid2-e1761583933519-220x160.jpg","width":220,"height":160,"mime-type":"image\/jpeg","filesize":11292,"source_url":"https:\/\/orfeostoryweb.com\/sosd\/wp-content\/uploads\/2025\/10\/Hagrid2-e1761583933519-220x160.jpg"},"woocommerce_single":{"file":"Hagrid2-e1761583933519-500x363.jpg","width":500,"height":363,"mime-type":"image\/jpeg","filesize":53580,"source_url":"https:\/\/orfeostoryweb.com\/sosd\/wp-content\/uploads\/2025\/10\/Hagrid2-e1761583933519-500x363.jpg"},"woocommerce_gallery_thumbnail":{"file":"Hagrid2-e1761583933519-100x100.jpg","width":100,"height":100,"mime-type":"image\/jpeg","filesize":4078,"source_url":"https:\/\/orfeostoryweb.com\/sosd\/wp-content\/uploads\/2025\/10\/Hagrid2-e1761583933519-100x100.jpg"}}},"alt_text":"","url":"","target":""},{"id":17715,"title":"Hagrid3","caption":"","full_image_url":"https:\/\/orfeostoryweb.com\/sosd\/wp-content\/uploads\/2025\/10\/Hagrid3-e1761583958274.jpg","thumbnail_image_url":"https:\/\/orfeostoryweb.com\/sosd\/wp-content\/uploads\/2025\/10\/Hagrid3-e1761583958274-150x150.jpg","large_srcset":"https:\/\/orfeostoryweb.com\/sosd\/wp-content\/uploads\/2025\/10\/Hagrid3-e1761583958274.jpg 610w, https:\/\/orfeostoryweb.com\/sosd\/wp-content\/uploads\/2025\/10\/Hagrid3-e1761583958274-300x214.jpg 300w, https:\/\/orfeostoryweb.com\/sosd\/wp-content\/uploads\/2025\/10\/Hagrid3-e1761583958274-220x157.jpg 220w, https:\/\/orfeostoryweb.com\/sosd\/wp-content\/uploads\/2025\/10\/Hagrid3-e1761583958274-500x357.jpg 500w","medium_srcset":"https:\/\/orfeostoryweb.com\/sosd\/wp-content\/uploads\/2025\/10\/Hagrid3-e1761583958274-300x214.jpg 300w, https:\/\/orfeostoryweb.com\/sosd\/wp-content\/uploads\/2025\/10\/Hagrid3-e1761583958274-220x157.jpg 220w, https:\/\/orfeostoryweb.com\/sosd\/wp-content\/uploads\/2025\/10\/Hagrid3-e1761583958274-500x357.jpg 500w, https:\/\/orfeostoryweb.com\/sosd\/wp-content\/uploads\/2025\/10\/Hagrid3-e1761583958274.jpg 610w","media_details":{"width":610,"height":435,"sizes":{"medium":{"file":"Hagrid3-e1761583958274-300x214.jpg","width":300,"height":214,"mime-type":"image\/jpeg","filesize":17533,"source_url":"https:\/\/orfeostoryweb.com\/sosd\/wp-content\/uploads\/2025\/10\/Hagrid3-e1761583958274-300x214.jpg"},"thumbnail":{"file":"Hagrid3-e1761583958274-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":6440,"source_url":"https:\/\/orfeostoryweb.com\/sosd\/wp-content\/uploads\/2025\/10\/Hagrid3-e1761583958274-150x150.jpg"},"woocommerce_thumbnail":{"file":"Hagrid3-e1761583958274-220x157.jpg","width":220,"height":157,"mime-type":"image\/jpeg","filesize":9343,"source_url":"https:\/\/orfeostoryweb.com\/sosd\/wp-content\/uploads\/2025\/10\/Hagrid3-e1761583958274-220x157.jpg"},"woocommerce_single":{"file":"Hagrid3-e1761583958274-500x357.jpg","width":500,"height":357,"mime-type":"image\/jpeg","filesize":50096,"source_url":"https:\/\/orfeostoryweb.com\/sosd\/wp-content\/uploads\/2025\/10\/Hagrid3-e1761583958274-500x357.jpg"},"woocommerce_gallery_thumbnail":{"file":"Hagrid3-e1761583958274-100x100.jpg","width":100,"height":100,"mime-type":"image\/jpeg","filesize":3367,"source_url":"https:\/\/orfeostoryweb.com\/sosd\/wp-content\/uploads\/2025\/10\/Hagrid3-e1761583958274-100x100.jpg"}}},"alt_text":"","url":"","target":""}]]}},"_links":{"self":[{"href":"https:\/\/orfeostoryweb.com\/sosd\/wp-json\/wp\/v2\/posts\/17714","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/orfeostoryweb.com\/sosd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/orfeostoryweb.com\/sosd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/orfeostoryweb.com\/sosd\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/orfeostoryweb.com\/sosd\/wp-json\/wp\/v2\/comments?post=17714"}],"version-history":[{"count":0,"href":"https:\/\/orfeostoryweb.com\/sosd\/wp-json\/wp\/v2\/posts\/17714\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/orfeostoryweb.com\/sosd\/wp-json\/wp\/v2\/media\/17717"}],"wp:attachment":[{"href":"https:\/\/orfeostoryweb.com\/sosd\/wp-json\/wp\/v2\/media?parent=17714"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/orfeostoryweb.com\/sosd\/wp-json\/wp\/v2\/categories?post=17714"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/orfeostoryweb.com\/sosd\/wp-json\/wp\/v2\/tags?post=17714"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}